{"id":1100,"date":"2016-03-03T16:35:16","date_gmt":"2016-03-03T15:35:16","guid":{"rendered":"http:\/\/www.actvism.org\/?p=1100"},"modified":"2020-11-06T17:48:59","modified_gmt":"2020-11-06T16:48:59","slug":"apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino","status":"publish","type":"post","link":"https:\/\/www.actvism.org\/en\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/","title":{"rendered":"Apple Wins Major Court Victory Against FBI in a Case Similar to San Bernardino &#8211; The Intercept"},"content":{"rendered":"<div class=\"container\">\n<div class=\"row justify-content-md-center\">\n<div class=\"col-md-8 pb-3\">\n<p>For the English article, visit the original source: <a href=\"https:\/\/theintercept.com\">The Intercept<\/a><\/p>\n<p>Link: <span style=\"color: #000080;\">https:\/\/theintercept.com\/2016\/02\/29\/apple-wins-major-court-victory-in-its-battle-against-fbi-in-a-case-similar-to-san-bernardino\/<\/span><br \/>\n<a dir=\"ltr\" href=\"https:\/\/l.facebook.com\/l.php?u=https%3A%2F%2Ftheintercept.com%2F2016%2F02%2F22%2Fsaudi-christmas-present%2F&amp;h=ZAQE601nx\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><span style=\"color: #000080;\"><br \/>\n<\/span><\/a><span style=\"color: #000080;\">P<\/span><span style=\"color: #000000;\">icture: W<a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/c\/c4\/Apple_Store_Carrousel_du_Louvre,_18_March_2011.jpg\" target=\"_blank\" rel=\"noopener noreferrer\">ikipedia<\/a><\/span><\/p>\n<hr \/>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>For the English article, visit the original source: The Intercept<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1,14],"tags":[35,165,341,347,104,346,93,68,103,348,74,71,343,344,345,57,58,277,100,350,349,59,113,342,102,276,65,30],"channel":[],"class_list":["post-1100","post","type-post","status-publish","format-standard","hentry","category-latest","category-politics","tag-actvism-munich","tag-aktivismus","tag-apple","tag-applevsfbi","tag-cia","tag-dea","tag-democracy","tag-edward-snowden","tag-fbi","tag-fbivsapple","tag-george-orwell","tag-glenn-greenwald","tag-ipad","tag-iphone","tag-iphone-5","tag-nsa","tag-privacy","tag-privatsspahre","tag-snowden","tag-snowden-quote","tag-snowden-zitat","tag-surveillance","tag-terrorism","tag-terrorismus","tag-the-intercept","tag-uberwachung","tag-whistleblower","tag-whistleblowers"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":true},"en":{"title":true,"content":true,"excerpt":true}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apple FBI : Apple erringt bedeutenden juristischen Sieg gegen FBI\u00a0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple Wins Major Court Victory Against FBI in a Case Similar to San Bernardino - The Intercept - acTVism\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/\" \/>\n<meta property=\"og:site_name\" content=\"acTVism\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/acTVism\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-03T15:35:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-06T16:48:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.actvism.org\/wp-content\/uploads\/2016\/03\/Snowdentweet-300x174.png\" \/>\n<meta name=\"author\" content=\"atv_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acTVismMunich\" \/>\n<meta name=\"twitter:site\" content=\"@acTVismMunich\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"atv_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/\"},\"author\":{\"name\":\"atv_admin\",\"@id\":\"https:\\\/\\\/www.actvism.org\\\/#\\\/schema\\\/person\\\/bc2c8684912eb2289fe0009f5ca451d6\"},\"headline\":\"Apple Wins Major Court Victory Against FBI in a Case Similar to San Bernardino &#8211; The Intercept\",\"datePublished\":\"2016-03-03T15:35:16+00:00\",\"dateModified\":\"2020-11-06T16:48:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/\"},\"wordCount\":364,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.actvism.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.actvism.org\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Snowdentweet-300x174.png\",\"keywords\":[\"acTVism Munich\",\"aktivismus\",\"apple\",\"applevsfbi\",\"CIA\",\"DEA\",\"Democracy\",\"Edward Snowden\",\"FBI\",\"fbivsapple\",\"George Orwell\",\"Glenn Greenwald\",\"ipad\",\"iphone\",\"iphone 5\",\"NSA\",\"privacy\",\"privatssp\u00e4hre\",\"Snowden\",\"snowden quote\",\"snowden zitat\",\"surveillance\",\"Terrorism\",\"terrorismus\",\"The Intercept\",\"\u00fcberwachung\",\"Whistleblower\",\"whistleblowers\"],\"articleSection\":[\"LATEST\",\"OUR CONTENT\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/\",\"url\":\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/\",\"name\":\"Apple FBI : Apple erringt bedeutenden juristischen Sieg gegen FBI\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.actvism.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.actvism.org\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Snowdentweet-300x174.png\",\"datePublished\":\"2016-03-03T15:35:16+00:00\",\"dateModified\":\"2020-11-06T16:48:59+00:00\",\"description\":\"Apple FBI : Apple erringt bedeutenden juristischen Sieg gegen FBI in einem Fall \u00e4hnlich wie San Bernadino. Dieser Artikel wurde von Glenn Greenwald\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.actvism.org\\\/latest\\\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.actvism.org\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Snowdentweet-300x174.png\",\"contentUrl\":\"https:\\\/\\\/www.actvism.org\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Snowdentweet-300x174.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.actvism.org\\\/#website\",\"url\":\"https:\\\/\\\/www.actvism.org\\\/\",\"name\":\"acTVism\",\"description\":\"information that moves\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.actvism.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.actvism.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.actvism.org\\\/#organization\",\"name\":\"acTVism Munich e.V.\",\"url\":\"https:\\\/\\\/www.actvism.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.actvism.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.actvism.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.actvism.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":200,\"height\":57,\"caption\":\"acTVism Munich e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.actvism.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/acTVism\",\"https:\\\/\\\/x.com\\\/acTVismMunich\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.actvism.org\\\/#\\\/schema\\\/person\\\/bc2c8684912eb2289fe0009f5ca451d6\",\"name\":\"atv_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53465926e4246ee1b807a849c23197531fd45c1bcd02682ada54ddb12eaa7a6d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53465926e4246ee1b807a849c23197531fd45c1bcd02682ada54ddb12eaa7a6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53465926e4246ee1b807a849c23197531fd45c1bcd02682ada54ddb12eaa7a6d?s=96&d=mm&r=g\",\"caption\":\"atv_admin\"},\"url\":\"https:\\\/\\\/www.actvism.org\\\/en\\\/author\\\/atv_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apple FBI : Apple erringt bedeutenden juristischen Sieg gegen FBI\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/","og_locale":"en_US","og_type":"article","og_title":"Apple Wins Major Court Victory Against FBI in a Case Similar to San Bernardino - The Intercept - acTVism","og_url":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/","og_site_name":"acTVism","article_publisher":"https:\/\/facebook.com\/acTVism","article_published_time":"2016-03-03T15:35:16+00:00","article_modified_time":"2020-11-06T16:48:59+00:00","og_image":[{"url":"https:\/\/www.actvism.org\/wp-content\/uploads\/2016\/03\/Snowdentweet-300x174.png","type":"","width":"","height":""}],"author":"atv_admin","twitter_card":"summary_large_image","twitter_creator":"@acTVismMunich","twitter_site":"@acTVismMunich","twitter_misc":{"Written by":"atv_admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/#article","isPartOf":{"@id":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/"},"author":{"name":"atv_admin","@id":"https:\/\/www.actvism.org\/#\/schema\/person\/bc2c8684912eb2289fe0009f5ca451d6"},"headline":"Apple Wins Major Court Victory Against FBI in a Case Similar to San Bernardino &#8211; The Intercept","datePublished":"2016-03-03T15:35:16+00:00","dateModified":"2020-11-06T16:48:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/"},"wordCount":364,"commentCount":0,"publisher":{"@id":"https:\/\/www.actvism.org\/#organization"},"image":{"@id":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.actvism.org\/wp-content\/uploads\/2016\/03\/Snowdentweet-300x174.png","keywords":["acTVism Munich","aktivismus","apple","applevsfbi","CIA","DEA","Democracy","Edward Snowden","FBI","fbivsapple","George Orwell","Glenn Greenwald","ipad","iphone","iphone 5","NSA","privacy","privatssp\u00e4hre","Snowden","snowden quote","snowden zitat","surveillance","Terrorism","terrorismus","The Intercept","\u00fcberwachung","Whistleblower","whistleblowers"],"articleSection":["LATEST","OUR CONTENT"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/","url":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/","name":"Apple FBI : Apple erringt bedeutenden juristischen Sieg gegen FBI\u00a0","isPartOf":{"@id":"https:\/\/www.actvism.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/#primaryimage"},"image":{"@id":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.actvism.org\/wp-content\/uploads\/2016\/03\/Snowdentweet-300x174.png","datePublished":"2016-03-03T15:35:16+00:00","dateModified":"2020-11-06T16:48:59+00:00","description":"Apple FBI : Apple erringt bedeutenden juristischen Sieg gegen FBI in einem Fall \u00e4hnlich wie San Bernadino. Dieser Artikel wurde von Glenn Greenwald","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.actvism.org\/latest\/apple-fbi-erringt-bedeutenden-juristischen-sieg-gegen-fbi-in-einem-fall-aehnlich-wie-san-bernadino\/#primaryimage","url":"https:\/\/www.actvism.org\/wp-content\/uploads\/2016\/03\/Snowdentweet-300x174.png","contentUrl":"https:\/\/www.actvism.org\/wp-content\/uploads\/2016\/03\/Snowdentweet-300x174.png"},{"@type":"WebSite","@id":"https:\/\/www.actvism.org\/#website","url":"https:\/\/www.actvism.org\/","name":"acTVism","description":"information that moves","publisher":{"@id":"https:\/\/www.actvism.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.actvism.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.actvism.org\/#organization","name":"acTVism Munich e.V.","url":"https:\/\/www.actvism.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.actvism.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.actvism.org\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.actvism.org\/wp-content\/uploads\/2020\/11\/logo.svg","width":200,"height":57,"caption":"acTVism Munich e.V."},"image":{"@id":"https:\/\/www.actvism.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/acTVism","https:\/\/x.com\/acTVismMunich"]},{"@type":"Person","@id":"https:\/\/www.actvism.org\/#\/schema\/person\/bc2c8684912eb2289fe0009f5ca451d6","name":"atv_admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/53465926e4246ee1b807a849c23197531fd45c1bcd02682ada54ddb12eaa7a6d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/53465926e4246ee1b807a849c23197531fd45c1bcd02682ada54ddb12eaa7a6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53465926e4246ee1b807a849c23197531fd45c1bcd02682ada54ddb12eaa7a6d?s=96&d=mm&r=g","caption":"atv_admin"},"url":"https:\/\/www.actvism.org\/en\/author\/atv_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.actvism.org\/en\/wp-json\/wp\/v2\/posts\/1100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.actvism.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actvism.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actvism.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actvism.org\/en\/wp-json\/wp\/v2\/comments?post=1100"}],"version-history":[{"count":0,"href":"https:\/\/www.actvism.org\/en\/wp-json\/wp\/v2\/posts\/1100\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.actvism.org\/en\/wp-json\/wp\/v2\/media?parent=1100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actvism.org\/en\/wp-json\/wp\/v2\/categories?post=1100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actvism.org\/en\/wp-json\/wp\/v2\/tags?post=1100"},{"taxonomy":"channel","embeddable":true,"href":"https:\/\/www.actvism.org\/en\/wp-json\/wp\/v2\/channel?post=1100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}